{"id":2636,"date":"2025-02-10T12:04:19","date_gmt":"2025-02-10T11:04:19","guid":{"rendered":"https:\/\/vasco-electronics.fr\/posts\/?p=2636"},"modified":"2026-02-03T12:45:42","modified_gmt":"2026-02-03T11:45:42","slug":"langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron","status":"publish","type":"post","link":"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/","title":{"rendered":"Les Langues de la Terre du Milieu : Sindarin, Khuzdul et Westron"},"content":{"rendered":"<p>Voici un autre article de notre s\u00e9rie sur les <a href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/\">langues<\/a> fictives cr\u00e9\u00e9es par J.R.R. Tolkien.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table de Mati\u00e8res<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a97691421162\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\" style='display:none' id=\"ez-toc-cssicon-toggle-item-6a97691421162\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Sindarin_%C2%ABLelfique%C2%BB_tel_quil_est_vu_par_les_autres\" >Sindarin : \u00abL\u2019elfique\u00bb\u00a0tel qu\u2019il est vu par les autres<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Les_origines_du_Sindarin\" >Les origines du Sindarin<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Le_Sindarin_dans_lhistoire_de_la_Terre_du_Milieu\" >Le Sindarin dans l&rsquo;histoire de la Terre du Milieu<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Lisons_un_peu_de_Sindarin\" >Lisons un peu de Sindarin<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Khuzdul_la_langue_secrete_des_Nains\" >Khuzdul : la langue secr\u00e8te des Nains<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Ce_que_nous_savons_sur_le_Khuzdul\" >Ce que nous savons sur le Khuzdul<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Systeme_decriture_du_Khuzdul\" >Syst\u00e8me d&rsquo;\u00e9criture du Khuzdul<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Lhistoire_du_Khuzdul\" >L&rsquo;histoire du Khuzdul<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Lisons_un_peu_de_Khuzdul\" >Lisons un peu de Khuzdul<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Westron_la_langue_commune_de_la_Terre_du_Milieu\" >Westron : la langue commune de la Terre du Milieu<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Histoire_du_Westron\" >Histoire du Westron<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Le_Westron_dans_les_livres\" >Le Westron dans les livres<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Ou_apprendre_le_Sindarin_le_Khuzdul_et_le_Westron\" >O\u00f9 apprendre le Sindarin, le Khuzdul et le Westron<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#Sindarin_Khuzdul_et_Westron_Conclusion\" >Sindarin, Khuzdul et Westron : Conclusion<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/langues-de-la-terre-du-milieu-sindarin-khuzdul-et-westron\/#En_resume\" >En r\u00e9sum\u00e9<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p>Sur notre blog, vous pouvez \u00e9galement trouver une analyse approfondie de la <a href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/quenya-parler-noir-mordor\/\">langue Quenya<\/a> et de la langue noire du Mordor, ainsi qu&rsquo;un article traitant bri\u00e8vement les langues les plus populaires de la Terre du Milieu en g\u00e9n\u00e9ral.<\/p>\n<p>Cette fois, nous aborderons plus en d\u00e9tail la langue Sindarin, d\u00e9couvrirons davantage la langue secr\u00e8te des Nains appel\u00e9e Khuzdul et apprendrons l&rsquo;histoire de la langue commune de la Terre du Milieu appel\u00e9e Westron.<\/p>\n<p>Sans plus tarder, commen\u00e7ons le voyage !<\/p>\n<div class=\"faq-section\">\n<h3>FAQ:<\/h3>\n<h4 class=\"question1\">Qu&rsquo;est-ce que la langue Sindarine ?<\/h4>\n<div class=\"answer1\">Le Sindarin est la langue la plus couramment associ\u00e9e aux Elfes. Elle a \u00e9t\u00e9 cr\u00e9\u00e9e par J.R.R Tolkien vers 1944 et appara\u00eet dans Le Seigneur des Anneaux.<\/div>\n<h4 class=\"question2\">Qu&rsquo;est-ce que le Khuzdul ?<\/h4>\n<div class=\"answer2\">Le Khuzdul est la langue secr\u00e8te des Nains. Elle a \u00e9t\u00e9 cr\u00e9\u00e9e par J.R.R. Tolkien et \u00e9tait fortement influenc\u00e9e par l&rsquo;h\u00e9breu. Les Nains utilisaient l&rsquo;\u00e9criture Cirith pour la noter et la gardaient secr\u00e8te, ne la parlant qu&rsquo;entre eux.<\/div>\n<h4 class=\"question3\">Qu&rsquo;est-ce que le Westron ?<\/h4>\n<div class=\"answer3\">Le Westron est la langue commune de la Terre du Milieu. Elle est issue de l&rsquo;Ad\u00fbnaic, la langue des N\u00famenor\u00e9ens, et \u00e9tait parl\u00e9e par presque toutes les cr\u00e9atures de la r\u00e9gion nord-ouest de la Terre du Milieu \u00e0 la fin du Troisi\u00e8me \u00c2ge.<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4943\" src=\"https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_02.jpg\" alt=\"sindarin\" width=\"1200\" height=\"700\" srcset=\"https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_02.jpg 1200w, https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_02-980x572.jpg 980w, https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_02-480x280.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Sindarin_%C2%ABLelfique%C2%BB_tel_quil_est_vu_par_les_autres\"><\/span>Sindarin : \u00abL\u2019elfique\u00bb\u00a0tel qu\u2019il est vu par les autres<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le Sindarin est la langue g\u00e9n\u00e9ralement associ\u00e9e aux Elfes. C&rsquo;est \u00e9galement la langue elfique la plus parl\u00e9e dans Le Seigneur des Anneaux.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Les_origines_du_Sindarin\"><\/span>Les origines du Sindarin<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Tolkien a cr\u00e9\u00e9 le Sindarin vers 1944. Il souhaitait que ce soit une langue de type gallois, qui serait li\u00e9e au <a href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/quenya-parler-noir-mordor\/\">Quenya<\/a> de la m\u00eame mani\u00e8re que le gallois est li\u00e9 au latin.<\/p>\n<p>L&rsquo;auteur du Seigneur des Anneaux a \u00e9galement \u00e9crit de nombreux travaux en Sindarin, car il voulait vraiment lui donner l&rsquo;impression d&rsquo;une <a href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/\">langue naturelle<\/a>. N\u00e9anmoins, Tolkien n&rsquo;a pas fourni une description d\u00e9taill\u00e9e de cette langue dans aucun de ses livres.<\/p>\n<p>Dans les ann\u00e9es 1970, de nombreux fans de Tolkien ont commenc\u00e9 \u00e0 \u00e9crire des po\u00e8mes, des textes, des phrases, des noms et m\u00eame des tatouages en Sindarin. Malgr\u00e9 le fait que le corpus total de son vocabulaire ne consistait qu&rsquo;en quelques centaines de mots, les fans ont fait fleurir cette langue fictive.<\/p>\n<p>Notez que Tolkien ne voulait pas que ses langues soient suffisamment compl\u00e8tes pour permettre une conversation. Par cons\u00e9quent, les textes nouvellement cr\u00e9\u00e9s en Sindarin, y compris les dialogues des films du Seigneur des Anneaux, utilisent souvent de nouveaux mots et de nouvelles structures grammaticales.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Le_Sindarin_dans_lhistoire_de_la_Terre_du_Milieu\"><\/span>Le Sindarin dans l&rsquo;histoire de la Terre du Milieu<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Dans le royaume de la Terre du Milieu, au Deuxi\u00e8me \u00c2ge, le Sindarin \u00e9tait une lingua franca parmi les Elfes et leurs amis. C&rsquo;est pourquoi \u00e0 la porte ouest de Moria, il y avait des inscriptions dans cette langue. Lorsque Frodon demande quel est le mot elfique pour ami, il veut savoir quel est le mot Sindarin pour ami.<\/p>\n<p>Cependant, le Troisi\u00e8me \u00c2ge a vu l&rsquo;ascension de la langue Westron, qui a remplac\u00e9 le Sindarin comme langue universelle de la Terre du Milieu. N\u00e9anmoins, le Westron \u00e9tait fortement influenc\u00e9 par son pr\u00e9d\u00e9cesseur elfique.<\/p>\n<p>Au Troisi\u00e8me \u00c2ge, cependant, le Sindarin \u00e9tait encore parl\u00e9 par certains habitants nobles de Minas Tirith. De plus, Aragorn, qui a \u00e9t\u00e9 \u00e9lev\u00e9 parmi les Elfes \u00e0 Fondcombe, pouvait le parler couramment.<\/p>\n<h4>Apprenons un peu de vocabulaire Sindarin<\/h4>\n<p>Il y avait environ 25 000 mots publi\u00e9s en Sindarin en 2008. Apprenons-en quelques-uns \u00e0 partir du tableau ci-dessous :<\/p>\n<table style=\"width: 303px;\" border=\"1\">\n<tbody>\n<tr>\n<th style=\"width: 122.125px;\">Sindarin<\/th>\n<th style=\"width: 164.875px;\">Anglais<\/th>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">amar<\/td>\n<td style=\"width: 164.875px;\">terre<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">aur<\/td>\n<td style=\"width: 164.875px;\">jour<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">d\u00fb<\/td>\n<td style=\"width: 164.875px;\">nuit<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">naur<\/td>\n<td style=\"width: 164.875px;\">feu<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">menel<\/td>\n<td style=\"width: 164.875px;\">ciel<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">daer<\/td>\n<td style=\"width: 164.875px;\">grand<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">benn<\/td>\n<td style=\"width: 164.875px;\">m\u00e2le<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">bess<\/td>\n<td style=\"width: 164.875px;\">femelle<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">nen<\/td>\n<td style=\"width: 164.875px;\">eau<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">corf<\/td>\n<td style=\"width: 164.875px;\">anneau<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 122.125px;\">fae<\/td>\n<td style=\"width: 164.875px;\">\u00e2me, esprit<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><span class=\"ez-toc-section\" id=\"Lisons_un_peu_de_Sindarin\"><\/span>Lisons un peu de Sindarin<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le livre du Seigneur des Anneaux pr\u00e9sente un long po\u00e8me \u00e9crit en langue Sindarie. Il s&rsquo;appelle A Elbereth Gilthoniel, et c&rsquo;est un hymne elfique adress\u00e9 \u00e0 Varda. Cette derni\u00e8re dite, Varda ou Elbereth, \u00e9tait l&rsquo;une des cr\u00e9atures ang\u00e9liques au service d&rsquo;Eru Il\u00favatar, l&rsquo;\u00e9quivalent du Dieu chr\u00e9tien.<\/p>\n<p>Le po\u00e8me est \u00e9crit en t\u00e9tram\u00e8tres iambiques et a \u00e9t\u00e9 compar\u00e9 aux hymnes catholiques romains \u00e0 Marie, m\u00e8re de J\u00e9sus.<\/p>\n<p>Malheureusement, Le Seigneur des Anneaux n&rsquo;inclut aucune traduction de la pi\u00e8ce. Elle est cependant d\u00e9crite dans les livres de la mani\u00e8re suivante :<\/p>\n<p>\u00ab Les douces syllabes du chant elfique tombaient comme de joyaux clairs de mots et de m\u00e9lodies m\u00e9lang\u00e9s. &lsquo;C&rsquo;est un chant pour Elbereth&rsquo;, dit Bilbo \u00bb (Le Seigneur des Anneaux, J.R.R. Tolkien)<\/p>\n<p>Il y a aussi une indication sur le sens plus tard dans le livre :<\/p>\n<p>\u00ab Bonne nuit ! Je vais faire une promenade, je crois, et regarder les \u00e9toiles d&rsquo;Elbereth dans le jardin. Dors bien ! \u00bb (Le Seigneur des Anneaux, J.R.R. Tolkien)<\/p>\n<p>Heureusement, The Road Goes On, la collection de partitions de 1967 \u00e9crite par le compositeur britannique Donald Swann pour accompagner la po\u00e9sie de la Terre du Milieu, inclut la traduction du po\u00e8me.<\/p>\n<h5>Voici le po\u00e8me en Sindarin :<\/h5>\n<p style=\"text-align: center;\">A Elbereth Gilthoniel<\/p>\n<p style=\"text-align: center;\">silivren penna m\u00edriel<\/p>\n<p style=\"text-align: center;\">o menel aglar elenath !<\/p>\n<p style=\"text-align: center;\">Na-chaered palan-d\u00edriel<\/p>\n<p style=\"text-align: center;\">o galadhremmin ennorath,<\/p>\n<p style=\"text-align: center;\">Fanuilos, le linnathon Everwhite,<\/p>\n<p style=\"text-align: center;\">nef aear, s\u00ed nef aearon !<\/p>\n<p style=\"text-align: center;\">A Elbereth Gilthoniel<\/p>\n<p style=\"text-align: center;\">o menel palan-diriel,<\/p>\n<p style=\"text-align: center;\">le nallon s\u00ed di\u2019nguruthos !<\/p>\n<p style=\"text-align: center;\">A tiro nin, Fanuilos !<\/p>\n<h5>Et voici la traduction en fran\u00e7ais :<\/h5>\n<p style=\"text-align: center;\">\u00d4 Elbereth Qui fait scintiller les \u00c9toiles<\/p>\n<p style=\"text-align: center;\">le blanc scintillant descend<\/p>\n<p style=\"text-align: center;\">\u00e9tincelant comme des joyaux<\/p>\n<p style=\"text-align: center;\">du firmament la gloire de l&rsquo;arm\u00e9e des \u00e9toiles !<\/p>\n<p style=\"text-align: center;\">De loin en loin, j&rsquo;ai regard\u00e9<\/p>\n<p style=\"text-align: center;\">depuis les terres du milieu enchev\u00eatr\u00e9es d&rsquo;arbres,<\/p>\n<p style=\"text-align: center;\">Fanuilos, vers toi je chanterai<\/p>\n<p style=\"text-align: center;\">de ce c\u00f4t\u00e9 de l&rsquo;oc\u00e9an, ici de ce c\u00f4t\u00e9 du Grand Oc\u00e9an !<\/p>\n<p>Cela conclut notre revue de la langue Sindarine. Plus loin dans l&rsquo;article, nous verrons o\u00f9 vous pouvez apprendre \u00e0 parler cette langue.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4942\" src=\"https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_04.jpg\" alt=\"Khuzdul\" width=\"1200\" height=\"700\" srcset=\"https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_04.jpg 1200w, https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_04-980x572.jpg 980w, https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_04-480x280.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Khuzdul_la_langue_secrete_des_Nains\"><\/span>Khuzdul : la langue secr\u00e8te des Nains<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>J.R.R. Tolkien a commenc\u00e9 \u00e0 d\u00e9velopper le Khuzdul avant la publication du Hobbit en 1937. Certains noms en Khuzdul sont m\u00eame apparus dans les versions ant\u00e9rieures du Silmarillion.<\/p>\n<p>L&rsquo;h\u00e9breu \u00e9tait la principale source d&rsquo;inspiration pour cette langue naine. Tolkien a \u00e9galement soulign\u00e9 certains parall\u00e8les entre les Juifs et les nains. Les deux \u00e9taient \u00e0 la fois locaux et \u00e9trangers dans leur propre pays.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Ce_que_nous_savons_sur_le_Khuzdul\"><\/span>Ce que nous savons sur le Khuzdul<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Malheureusement, il n&rsquo;y a pas beaucoup de vocabulaire Khuzdul \u00e0 trouver. N\u00e9anmoins, Tolkien a affirm\u00e9 qu&rsquo;il avait d\u00e9velopp\u00e9 cette langue \u00e0 un certain degr\u00e9, y compris la phonologie et la grammaire.<\/p>\n<p>La structure syllabique du Khuzdul rendait cette langue rude, selon les Elfes, qui trouvaient sa sonorit\u00e9 laide. En fait, Tolkien lui-m\u00eame a d\u00e9clar\u00e9 que la langue naine \u00e9tait plus cacophonique que belle.<\/p>\n<p>Le Khuzdul a \u00e9t\u00e9 donn\u00e9 aux Nains par Aul\u00eb \u2014 un forgeron divin et l&rsquo;un des \u00eatres immortels qui ont particip\u00e9 \u00e0 la cr\u00e9ation d&rsquo;Arda (l&rsquo;\u00e9quivalent de la Terre r\u00e9elle). Et, comme les Nains montraient un profond respect pour Aul\u00eb, peu de changements ont \u00e9t\u00e9 apport\u00e9s au Khuzdul au fil du temps.<\/p>\n<p>Les Nains utilisaient le Cirith, un script cr\u00e9\u00e9 par Tolkien et bas\u00e9 sur les runes du monde r\u00e9el, pour \u00e9crire le Khuzdul. Les Nains ont adopt\u00e9 les runes des Elfes et les ont modifi\u00e9es pour \u00eatre plus repr\u00e9sentatives de la langue Khuzdul.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Systeme_decriture_du_Khuzdul\"><\/span>Syst\u00e8me d&rsquo;\u00e9criture du Khuzdul<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ils utiliseraient deux m\u00e9thodes d&rsquo;\u00e9criture diff\u00e9rentes. L&rsquo;une d&rsquo;elles a \u00e9t\u00e9 d\u00e9velopp\u00e9e par les habitants de la Moria \u00e0 Khazad-d\u00fbm et la seconde provenait d&rsquo;Erebor \u2014 La Montagne Solitaire connue du Hobbit.<\/p>\n<p>Jetons un coup d&rsquo;\u0153il \u00e0 un cri de bataille nain \u00e9crit dans les versions de Moria et d&rsquo;Erebor du Cirith.<\/p>\n<p>Moria :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2652 alignleft\" src=\"https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/03\/Screenshot-2024-02-02-160812.png.webp\" alt=\"moria\" width=\"595\" height=\"50\" srcset=\"https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/03\/Screenshot-2024-02-02-160812.png.webp 595w, https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/03\/Screenshot-2024-02-02-160812.png-480x40.webp 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 595px, 100vw\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>(Source : Wikip\u00e9dia)<\/p>\n<p>et la version romanis\u00e9e :<\/p>\n<p><strong>baruk khaz\u00e2d khaz\u00e2d \u02bbaim\u00eanu<\/strong><\/p>\n<p>Erebor :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2653\" src=\"https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/03\/Screenshot-2024-02-02-161140.png.webp\" alt=\"erebor\" width=\"632\" height=\"66\" srcset=\"https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/03\/Screenshot-2024-02-02-161140.png.webp 632w, https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/03\/Screenshot-2024-02-02-161140.png-480x50.webp 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 632px, 100vw\" \/><\/p>\n<p>(Source : Wikipedia)<\/p>\n<p>et la version romanis\u00e9e :<\/p>\n<p><strong>baruk khaz\u00e2d khaz\u00e2d aim\u00eanu<\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Lhistoire_du_Khuzdul\"><\/span>L&rsquo;histoire du Khuzdul<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>En ce qui concerne l&rsquo;histoire interne de cette langue, peu de choses sont connues sur le Khuzdul. C&rsquo;est principalement parce que les Nains la gardaient secr\u00e8te. Ils croyaient que cette langue leur \u00e9tait r\u00e9serv\u00e9e uniquement, donc ils l&rsquo;enseignaient avec r\u00e9ticence \u00e0 d&rsquo;autres races. De plus, ils la rendaient rude et difficile \u00e0 utiliser, afin qu&rsquo;il soit tr\u00e8s difficile de l&rsquo;apprendre et de la parler.<\/p>\n<p>En fait, les Nains utilisaient d&rsquo;autres langues pour communiquer avec les \u00e9trangers (par exemple, le Westron). Ils utilisaient le Khuzdul uniquement pour parler entre eux.<\/p>\n<p>Le plus haut niveau de secret \u00e9tait r\u00e9serv\u00e9 \u00e0 leurs vrais noms, que les Nains consid\u00e9raient tr\u00e8s intimes. Les noms des Nains que nous connaissons tous des livres et des films sont tous des \u00ab\u00a0noms ext\u00e9rieurs\u00a0\u00bb r\u00e9serv\u00e9s aux autres races.<\/p>\n<p>Cependant, en raison d&rsquo;une amiti\u00e9 \u00e9troite avec certains humains de la Terre du Milieu, ils utilisaient \u00e9galement le Khuzdul entre eux en leur pr\u00e9sence.<\/p>\n<p>Apprenons quelques mots de vocabulaire d\u00e8s maintenant :<\/p>\n<table style=\"width: 252px;\" border=\"1\">\n<tbody>\n<tr>\n<th style=\"width: 100.453px;\">Khuzdul<\/th>\n<th style=\"width: 135.547px;\">Fran\u00e7ais<\/th>\n<\/tr>\n<tr>\n<td style=\"width: 100.453px;\">agl\u00e2b<\/td>\n<td style=\"width: 135.547px;\">langue<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100.453px;\">duban<\/td>\n<td style=\"width: 135.547px;\">vall\u00e9e<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100.453px;\">gundu<\/td>\n<td style=\"width: 135.547px;\">salle souterraine<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100.453px;\">Khuzd<\/td>\n<td style=\"width: 135.547px;\">Nain<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100.453px;\">uzn<\/td>\n<td style=\"width: 135.547px;\">ombre<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100.453px;\">zigil<\/td>\n<td style=\"width: 135.547px;\">argent (couleur)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100.453px;\">kheled<\/td>\n<td style=\"width: 135.547px;\">verre<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100.453px;\">felak<\/td>\n<td style=\"width: 135.547px;\">outil pour tailler la pierre<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100.453px;\">uzbad<\/td>\n<td style=\"width: 135.547px;\">seigneur<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100.453px;\">shath\u00fbr<\/td>\n<td style=\"width: 135.547px;\">nuage(s)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><span class=\"ez-toc-section\" id=\"Lisons_un_peu_de_Khuzdul\"><\/span>Lisons un peu de Khuzdul<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Voici 3 phrases en Khuzdul que l&rsquo;on peut trouver dans certaines \u0153uvres de J.R.R. Tolkien. Voyons ce qu&rsquo;elles signifient en fran\u00e7ais :<\/p>\n<ul>\n<li>Balin Fundinul Uzbad Khazadd\u00fbmu \u2014 Balin, Fils de Fundin, Seigneur de la Moria<\/li>\n<li>baruk Khaz\u00e2d \u2014 haches des Nains<\/li>\n<li>Khaz\u00e2d ai-m\u00eanu \u2014 les Nains sont sur vous !<\/li>\n<\/ul>\n<p>Nous pouvons maintenant voir que le cri de bataille que nous avons examin\u00e9 plus t\u00f4t peut \u00eatre grossi\u00e8rement compris comme \u00ab\u00a0Haches des Nains, les Nains sont sur vous !\u00a0\u00bb.<\/p>\n<p>Cela conclut notre exploration du Khuzdul. Restez avec nous jusqu&rsquo;\u00e0 la fin pour voir o\u00f9 vous pouvez apprendre un peu de cette langue.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4941\" src=\"https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_03.jpg\" alt=\"westron\" width=\"1200\" height=\"700\" srcset=\"https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_03.jpg 1200w, https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_03-980x572.jpg 980w, https:\/\/vasco-electronics.fr\/posts\/wp-content\/uploads\/2025\/02\/Blog_2026_sindarin_03-480x280.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Westron_la_langue_commune_de_la_Terre_du_Milieu\"><\/span>Westron : la langue commune de la Terre du Milieu<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u00c0 l&rsquo;origine, le Westron \u00e9tait la langue des D\u00fanedains de la Terre du Milieu, mais \u00e0 la fin du Troisi\u00e8me \u00c2ge, elle \u00e9tait utilis\u00e9e par la majorit\u00e9 des cr\u00e9atures de la r\u00e9gion nord-ouest de ce monde fictif.<\/p>\n<p>La langue Westron est issue de l&rsquo;Ad\u00fbnaic \u2014 la langue des N\u00famenor\u00e9ens. Les Hommes de N\u00famenor l&rsquo;ont apport\u00e9e en Terre du Milieu lorsqu&rsquo;ils y ont \u00e9tabli des avant-postes commerciaux au Deuxi\u00e8me \u00c2ge.<\/p>\n<p>Le Westron est apparu comme une langue cr\u00e9ole apr\u00e8s que l&rsquo;Ad\u00fbnaic a fusionn\u00e9 avec le parler des Hommes du Cr\u00e9puscule.<\/p>\n<p>Note : Il y avait 3 types d&rsquo;hommes vivant en Terre du Milieu au Troisi\u00e8me \u00c2ge. Il y avait : les Hommes de Haute lign\u00e9e \u2014 les Gondoriens, nobles descendants de N\u00famenor ; les Hommes des T\u00e9n\u00e8bres \u2014 les Haradrim, les Orientaux, les Variags, les N\u00famenor\u00e9ens Noirs, les Corsaires d&rsquo;Umbar, les Demi-Trolls, qui servaient Sauron ; les Hommes du Cr\u00e9puscule ou Hommes du Milieu \u2014 autres Hommes en Terre du Milieu qui descendaient des Edain, anciens Hommes qui avaient combattu aux c\u00f4t\u00e9s des Elfes dans la guerre contre Morgoth. Le terme &lsquo;Hommes du Cr\u00e9puscule&rsquo; refl\u00e8te l&rsquo;attitude des Gondoriens envers eux \u2014 ils pensaient que les Hommes du Milieu n&rsquo;\u00e9taient pas leurs ennemis, mais n&rsquo;\u00e9taient pas assez nobles pour \u00eatre des Hommes de Haute lign\u00e9e.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Histoire_du_Westron\"><\/span>Histoire du Westron<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Apr\u00e8s la chute de N\u00famenor (qui peut \u00eatre l&rsquo;\u00e9quivalent en Terre du Milieu \u00e0 la fois du Mythe du D\u00e9luge et de la destruction de Sodome et Gomorrhe), les N\u00famenor\u00e9ens ont abandonn\u00e9 l&rsquo;Ad\u00fbnaic qui \u00e9tait alors parl\u00e9 par les Hommes du Cr\u00e9puscule. Devenant une langue rude avec une influence Khuzdul, le Westron s&rsquo;est adouci gr\u00e2ce aux influences de langues telles que le Sindarin.<\/p>\n<p>Au Troisi\u00e8me \u00c2ge, le Westron \u00e9tait parl\u00e9 par presque tous les Hommes de la Terre du Milieu, ainsi que par d&rsquo;autres cr\u00e9atures, y compris les Hobbits (cependant, ils ont d\u00e9velopp\u00e9 leur propre dialecte du Westron appel\u00e9 Hobbitique). Cette langue commune de la Terre du Milieu \u00e9tait \u00e9galement utilis\u00e9e par les Nains comme leur langue publique.<\/p>\n<p>En ce qui concerne les Hommes de la Terre du Milieu, le Westron a \u00e9galement \u00e9t\u00e9 adopt\u00e9 par la cr\u00e9ature m\u00e9tamorphe appel\u00e9e Beorn, ainsi que par les habitants de la ville au bord du lac pr\u00e8s de la Montagne Solitaire. Les exemples d&rsquo;humains qui n&rsquo;utilisaient pas le Westron \u00e9taient les Rohirrim, les Dr\u00faedains et les Hommes de Dunland.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Le_Westron_dans_les_livres\"><\/span>Le Westron dans les livres<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le Westron \u00e9tait \u00e9galement la langue parl\u00e9e et comprise par les protagonistes du Hobbit et du Seigneur des Anneaux. C&rsquo;est pourquoi on croit souvent \u00e0 tort que le westron \u00e9tait simplement de l&rsquo;anglais. En fait, Tolkien a fourni \u00e0 ses lecteurs la \u00ab traduction anglaise \u00bb de cette langue commune de la Terre du Milieu.<\/p>\n<p>Les noms des personnages, tels que Frodon, Sam et Pippin, n&rsquo;\u00e9taient pas leurs v\u00e9ritables noms. Leurs \u00e9quivalents en Westron \u00e9taient Maura, Ban et Razar.<\/p>\n<p>Jetons un coup d&rsquo;\u0153il au tableau ci-dessous pour en apprendre davantage sur le vocabulaire Westron :<\/p>\n<table style=\"width: 316px;\" border=\"1\">\n<tbody>\n<tr>\n<th style=\"width: 112.844px;\">Westron<\/th>\n<th style=\"width: 187.156px;\">Fran\u00e7ais<\/th>\n<\/tr>\n<tr>\n<td style=\"width: 112.844px;\">Karningul<\/td>\n<td style=\"width: 187.156px;\">Fondcombe<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 112.844px;\">Labin-nec<\/td>\n<td style=\"width: 187.156px;\">Cul-de-sac<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 112.844px;\">kuduk<\/td>\n<td style=\"width: 187.156px;\">hobbit<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 112.844px;\">banakil<\/td>\n<td style=\"width: 187.156px;\">semi-homme<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 112.844px;\">branda<\/td>\n<td style=\"width: 187.156px;\">terre frontali\u00e8re<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 112.844px;\">Branda-n\u00een<\/td>\n<td style=\"width: 187.156px;\">Brandevin (le nom de la rivi\u00e8re)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 112.844px;\">Bilba Labingi<\/td>\n<td style=\"width: 187.156px;\">Bilbo Baggins<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 112.844px;\">Inc\u00e1nus<\/td>\n<td style=\"width: 187.156px;\">Gandalf<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 112.844px;\">orka<\/td>\n<td style=\"width: 187.156px;\">orc<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 112.844px;\">narag<\/td>\n<td style=\"width: 187.156px;\">nain<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Vous pouvez voir qu&rsquo;il ressemble au Khuzdul, mais il est bien plus doux gr\u00e2ce aux influences de la langue Sindarine.<\/p>\n<p>Cela conclut notre exploration du Westron. Jetons maintenant un coup d&rsquo;\u0153il aux sources fiables pour apprendre les langues de la Terre du Milieu.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ou_apprendre_le_Sindarin_le_Khuzdul_et_le_Westron\"><\/span>O\u00f9 apprendre le Sindarin, le Khuzdul et le Westron<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Pour \u00eatre honn\u00eate, la meilleure source d&rsquo;information sur les langues mentionn\u00e9es ci-dessus se trouve dans les appendices du Retour du Roi. Cependant, vous pouvez apprendre beaucoup sur <a href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/les-langues-de-tolkien\/\">les langues de Tolkien<\/a> aupr\u00e8s de The Elfish Linguistic Fellowship (abr\u00e9g\u00e9e E.L.F).<\/p>\n<p>Il s&rsquo;agit d&rsquo;une organisation internationale qui examine les langues fictives cr\u00e9\u00e9es par J.R.R. Tolkien. elle publie deux journaux imprim\u00e9s : Vinyar Tengwar et Parma Eldalamberon. Elle a \u00e9galement son propre journal en ligne appel\u00e9 Tengwesti\u00eb.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Sindarin_Khuzdul_et_Westron_Conclusion\"><\/span>Sindarin, Khuzdul et Westron : Conclusion<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Malgr\u00e9 le fait que Le Seigneur des Anneaux a \u00e9t\u00e9 publi\u00e9 il y a plus d&rsquo;un demi-si\u00e8cle, l&rsquo;\u0153uvre de J.R.R. Tolkien est toujours aussi populaire qu&rsquo;elle l&rsquo;\u00e9tait il y a des ann\u00e9es, peut-\u00eatre m\u00eame plus maintenant.<\/p>\n<p>Nous n&rsquo;avons pas souvent entendu <a href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/les-langues-de-tolkien\/\">les langues de Tolkien<\/a> dans l&rsquo;adaptation du livre par Peter Jackson, mais, heureusement, il existe beaucoup de mat\u00e9riaux sur les parlers de la Terre du Milieu \u00e9crits par l&rsquo;auteur lui-m\u00eame.<\/p>\n<p>Et si vous avez une passion pour l&rsquo;apprentissage des langues, mais pas n\u00e9cessairement le temps et la motivation, assurez-vous de consulter notre magasin. Avec notre tout dernier appareil autonome, le <a href='https:\/\/vasco-electronics.fr\/traducteur-vocal\/vasco-translator-v4'>Vasco Translator V4<\/a>, vous avez 112 langues dans votre poche ! Peut-\u00eatre m\u00eame un jour le Sindarin, le Khuzdul et le Westron aussi\u2026<\/p>\n<h3><span class=\"ez-toc-section\" id=\"En_resume\"><\/span>En r\u00e9sum\u00e9<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le Sindarin est la langue elfique la plus associ\u00e9e au Seigneur des Anneaux, et a \u00e9t\u00e9 d\u00e9velopp\u00e9 par Tolkien vers 1944. C&rsquo;\u00e9tait une langue cr\u00e9ole, fortement influenc\u00e9e par le gallois et le <a href=\"https:\/\/vasco-electronics.fr\/posts\/langues\/quenya-parler-noir-mordor\/\">Quenya<\/a>, et \u00e9tait la langue commune de la Terre du Milieu au Deuxi\u00e8me \u00c2ge. Le Khuzdul est la langue secr\u00e8te des nains, cr\u00e9\u00e9e par Tolkien et bas\u00e9e sur l&rsquo;h\u00e9breu. Les nains la gardaient secr\u00e8te et l&rsquo;utilisaient uniquement entre eux, utilisant le Westron comme leur langue publique. Le Westron est une langue cr\u00e9ole r\u00e9sultant de la fusion de l&rsquo;Ad\u00fbnaic et du parler des Hommes du Cr\u00e9puscule. Elle \u00e9tait utilis\u00e9e par presque toutes les cr\u00e9atures de la r\u00e9gion nord-ouest de la Terre du Milieu au Troisi\u00e8me \u00c2ge, et \u00e9tait la langue parl\u00e9e et comprise par tous les protagonistes du Hobbit et du Seigneur des Anneaux. Pour en savoir plus sur le Sindarin, le Khuzdul et le Westron, on peut consulter le journal en ligne de The Elfish Linguistic Fellowship, Tengwesti\u00eb, ainsi que d&rsquo;autres sources.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici un autre article de notre s\u00e9rie sur les langues fictives cr\u00e9\u00e9es par J.R.R. Tolkien. Sur notre blog, vous pouvez \u00e9galement trouver une analyse approfondie de la langue Quenya et de la langue noire du Mordor, ainsi qu&rsquo;un article traitant bri\u00e8vement les langues les plus populaires de la Terre du Milieu en g\u00e9n\u00e9ral. Cette fois, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":4598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[22],"tags":[32],"class_list":["post-2636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-langues","tag-r-faber"],"_links":{"self":[{"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/posts\/2636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/comments?post=2636"}],"version-history":[{"count":9,"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/posts\/2636\/revisions"}],"predecessor-version":[{"id":4944,"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/posts\/2636\/revisions\/4944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/media\/4598"}],"wp:attachment":[{"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/media?parent=2636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/categories?post=2636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vasco-electronics.fr\/posts\/wp-json\/wp\/v2\/tags?post=2636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}